{"id":5803,"count":0,"description":"","link":"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/zo-de\/","name":"ZO","slug":"zo-de","taxonomy":"caratteristica-prodotto","parent":4953,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>- S\u2022CAB<\/title>\n<meta name=\"description\" content=\"S\u2022CAB ZO Finish - Verzinkter matt lackierter stahl, geriffelte ausf\u00fchrung - ZO - Vertiefen Sie die technischen Merkmale der S\u2022CAB-Produkte: Materialien, Farben, Formen, Oberfl\u00e4chen und Zertifizierungen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/zo-de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- S\u2022CAB\" \/>\n<meta property=\"og:description\" content=\"S\u2022CAB ZO Finish - Verzinkter matt lackierter stahl, geriffelte ausf\u00fchrung - ZO - Vertiefen Sie die technischen Merkmale der S\u2022CAB-Produkte: Materialien, Farben, Formen, Oberfl\u00e4chen und Zertifizierungen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/zo-de\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u2022CAB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/zo-de\/\",\"url\":\"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/zo-de\/\",\"name\":\"- S\u2022CAB\",\"isPartOf\":{\"@id\":\"https:\/\/www.s-cab.it\/de\/#website\"},\"description\":\"S\u2022CAB ZO Finish - Verzinkter matt lackierter stahl, geriffelte ausf\u00fchrung - ZO - Vertiefen Sie die technischen Merkmale der S\u2022CAB-Produkte: Materialien, Farben, Formen, Oberfl\u00e4chen und Zertifizierungen.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/zo-de\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/zo-de\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.s-cab.it\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finish\",\"item\":\"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/finish\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Verzinkter matt lackierter stahl, geriffelte ausf\u00fchrung\",\"item\":\"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/verzinkter-matt-lackierter-stahl-geriffelte-ausfuhrung\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"ZO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.s-cab.it\/de\/#website\",\"url\":\"https:\/\/www.s-cab.it\/de\/\",\"name\":\"S\u2022CAB\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.s-cab.it\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- S\u2022CAB","description":"S\u2022CAB ZO Finish - Verzinkter matt lackierter stahl, geriffelte ausf\u00fchrung - ZO - Vertiefen Sie die technischen Merkmale der S\u2022CAB-Produkte: Materialien, Farben, Formen, Oberfl\u00e4chen und Zertifizierungen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/zo-de\/","og_locale":"de_DE","og_type":"article","og_title":"- S\u2022CAB","og_description":"S\u2022CAB ZO Finish - Verzinkter matt lackierter stahl, geriffelte ausf\u00fchrung - ZO - Vertiefen Sie die technischen Merkmale der S\u2022CAB-Produkte: Materialien, Farben, Formen, Oberfl\u00e4chen und Zertifizierungen.","og_url":"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/zo-de\/","og_site_name":"S\u2022CAB","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/zo-de\/","url":"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/zo-de\/","name":"- S\u2022CAB","isPartOf":{"@id":"https:\/\/www.s-cab.it\/de\/#website"},"description":"S\u2022CAB ZO Finish - Verzinkter matt lackierter stahl, geriffelte ausf\u00fchrung - ZO - Vertiefen Sie die technischen Merkmale der S\u2022CAB-Produkte: Materialien, Farben, Formen, Oberfl\u00e4chen und Zertifizierungen.","breadcrumb":{"@id":"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/zo-de\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/zo-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.s-cab.it\/de\/"},{"@type":"ListItem","position":2,"name":"Finish","item":"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/finish\/"},{"@type":"ListItem","position":3,"name":"Verzinkter matt lackierter stahl, geriffelte ausf\u00fchrung","item":"https:\/\/www.s-cab.it\/de\/caratteristica-prodotto\/verzinkter-matt-lackierter-stahl-geriffelte-ausfuhrung\/"},{"@type":"ListItem","position":4,"name":"ZO"}]},{"@type":"WebSite","@id":"https:\/\/www.s-cab.it\/de\/#website","url":"https:\/\/www.s-cab.it\/de\/","name":"S\u2022CAB","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.s-cab.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.s-cab.it\/de\/wp-json\/wp\/v2\/caratteristica-prodotto\/5803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.s-cab.it\/de\/wp-json\/wp\/v2\/caratteristica-prodotto"}],"about":[{"href":"https:\/\/www.s-cab.it\/de\/wp-json\/wp\/v2\/taxonomies\/caratteristica-prodotto"}],"up":[{"embeddable":true,"href":"https:\/\/www.s-cab.it\/de\/wp-json\/wp\/v2\/caratteristica-prodotto\/4953"}],"wp:post_type":[{"href":"https:\/\/www.s-cab.it\/de\/wp-json\/wp\/v2\/prodotti?caratteristica-prodotto=5803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}